{"id":3485,"date":"2024-08-29T04:18:58","date_gmt":"2024-08-28T20:18:58","guid":{"rendered":"https:\/\/www.jinpinlub.com\/?post_type=product&#038;p=3485"},"modified":"2025-06-06T19:33:47","modified_gmt":"2025-06-06T11:33:47","slug":"distributore-di-sistema-di-lubrificazione-centralizzata-progressiva-jsv","status":"publish","type":"product","link":"https:\/\/www.jinpinlub.com\/it\/product\/jsv-progressive-centralized-lubrication-system-distributor\/","title":{"rendered":"Distributore di sistema di lubrificazione centralizzata progressiva JSV"},"content":{"rendered":"<h2>Caratteristiche<\/h2>\n<p><span id=\"input-sentence~0\">Distribuzione progressiva: ogni uscita del distributore JSV rilascia grasso in sequenza, garantendo che ogni punto di lubrificazione sia ben lubrificato.<br \/>\nTolleranza ad alta pressione: il limite di tolleranza della pressione di esercizio per i distributori \u00e8 di 300 bar, quindi adatti ad ambienti ad alta pressione.<\/span><span id=\"input-sentence~1\"><br \/>\nDesign multi-uscita: disponibili da 6 a 14 uscite, ciascuna con una cilindrata di 0,2 cc\/ciclo.<br \/>\nResistenza alle alte e basse temperature: grazie alla struttura di tenuta metallica, pu\u00f2 funzionare stabilmente anche in condizioni di lavoro difficili, in un intervallo di temperatura compreso tra -20\u00b0C e 80\u00b0C.<\/span><span id=\"input-sentence~2\"><br \/>\nMateriale resistente: realizzato in acciaio al carbonio e lega nichelata, ha un&#039;eccellente resistenza alla corrosione e una grande durata.<\/span><\/p>\n<h2>Specificazione<\/h2>\n<table>\n<tbody>\n<tr>\n<td>Principio di funzionamento<\/td>\n<td>Dispositivi di misurazione<\/td>\n<\/tr>\n<tr>\n<td>Numero di punti vendita<\/td>\n<td>6-20<\/td>\n<\/tr>\n<tr>\n<td>Quantit\u00e0 di dosaggio<\/td>\n<td>0,2 ml\/ciclo<\/td>\n<\/tr>\n<tr>\n<td>Lubrificante<\/td>\n<td>Grasso fino a NLGI 2, olio 32-220cSt@40\u2103<\/td>\n<\/tr>\n<tr>\n<td>Temperatura di esercizio<\/td>\n<td>da \u201320 a +80 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Pressione di esercizio<\/td>\n<td>Pressione massima 300 bar<\/td>\n<\/tr>\n<tr>\n<td>Materiale<\/td>\n<td>Zincato nero<\/td>\n<\/tr>\n<tr>\n<td>Ingresso di collegamento<\/td>\n<td>\u03a66\/\u03a68 (M10x1)<\/td>\n<\/tr>\n<tr>\n<td>Presa di collegamento<\/td>\n<td>\u03a66\/\u03a68 (M10x1)<\/td>\n<\/tr>\n<tr>\n<td>Posizione di montaggio<\/td>\n<td>Qualunque<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Applicazione<\/h2>\n<p><span id=\"input-sentence~2\">Veicoli e macchinari edili: i dispositivi di dosaggio JINPINLUB JSV sono adatti a vari tipi di sistemi di lubrificazione centralizzata di veicoli e macchinari edili pesanti.<br \/>\nIl dispositivo di misurazione JSV pu\u00f2 essere ampiamente utilizzato in molti tipi di apparecchiature di produzione, come macchine utensili, macchinari per la plastica e macchinari per la carta.<\/span><span id=\"input-sentence~3\"><br \/>\nGenerazione di energia eolica: il dispositivo di misurazione JSV pu\u00f2 essere utilizzato nelle apparecchiature di generazione di energia eolica per mantenere una lubrificazione affidabile e ridurre la frequenza della manutenzione. Macchinari per stampa e imballaggio: molti dispositivi di misurazione JSV sono utilizzati internamente nelle macchine per stampa e imballaggio per un funzionamento regolare delle apparecchiature.<\/span><\/p>\n<h2>Manuali<\/h2>\n<div class=\"sdm_download_button_box_default\"><div class=\"sdm_download_link\"><a href=\"https:\/\/www.jinpinlub.com\/it\/?sdm_process_download=1&download_id=2474\" class=\"sdm_download white\" title=\"Privato: JSV Progressive Distributor\" target=\"&quot;_blank&quot;\">Visualizza la scheda tecnica - Distributore JSV<\/a><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Il distributore JINPINLUB JSV \u00e8 un dispositivo progettato per sistemi di lubrificazione progressiva complessi. Pu\u00f2 funzionare in sistemi di lubrificazione centralizzata a grasso ad alta pressione e distribuire quantitativamente il lubrificante scaricato dalla pompa di lubrificazione a ciascun punto di lubrificazione.<\/p>","protected":false},"featured_media":3483,"template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":""},"product_brand":[],"product_cat":[44,41],"product_tag":[261,262,100],"class_list":{"0":"post-3485","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-progressive-grease-dividers","7":"product_cat-progressive-grease-systems","8":"product_tag-grease-dispenser-valve","9":"product_tag-grease-feeder","10":"product_tag-grease-metering-valve","12":"entry","13":"has-media","15":"first","16":"instock","17":"shipping-taxable","18":"product-type-external","19":"col","20":"span_1_of_3","21":"owp-content-center","22":"owp-thumbs-layout-horizontal","23":"owp-btn-very-big","24":"owp-tabs-layout-horizontal"},"_links":{"self":[{"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/product\/3485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/media\/3483"}],"wp:attachment":[{"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/media?parent=3485"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/product_brand?post=3485"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/product_cat?post=3485"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.jinpinlub.com\/it\/wp-json\/wp\/v2\/product_tag?post=3485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}